{"id":1097,"date":"2017-10-02T11:17:43","date_gmt":"2017-10-02T14:17:43","guid":{"rendered":"http:\/\/nyemba.unilab.edu.br\/?p=1097"},"modified":"2017-10-02T14:44:34","modified_gmt":"2017-10-02T17:44:34","slug":"encontro-nyemba","status":"publish","type":"post","link":"https:\/\/nyemba.unilab.edu.br\/index.php\/2017\/10\/02\/encontro-nyemba\/","title":{"rendered":"Encontro Nyemba"},"content":{"rendered":"<h3><span style=\"color: #800000;\"><strong>Prezados e Prezadas membros do Nyemba,\u00a0<\/strong><\/span><\/h3>\n<div>Convidamos @ tod@s para participar da nossa primeira reuni\u00e3o do segundo semestre que acontecer\u00e1 dia\u00a0<b>10 de outubro de 2017<\/b>, \u00e0s\u00a0<b>9:30 (Sala 04).\u00a0<\/b><\/div>\n<div><\/div>\n<div>Nesse dia iremos discutir o texto Godoi, Emilia. O sistema do lugar que faz parte das discuss\u00f5es sobre Territ\u00f3rio, Identidade e Mem\u00f3ria que ser\u00e3o levadas a cabo durante este per\u00edodo.<\/div>\n<div><\/div>\n<div>\n<p><strong><span style=\"color: #808080;\">Link:\u00a0<a href=\"https:\/\/drive.google.com\/file\/d\/0B7G8C4JphG55Vk5LQjdhVUN4bFE\/view\" target=\"_blank\" rel=\"attachment wp-att-1103 noopener\">GODOI, Emilia; NEIMEYER, Ana Maria (orgs). Al\u00e9m dos Territ\u00f3rios: para um di\u00e1logo entre a etnologia ind\u00edgena os estudos rurais e os estudos urbanos. Campinas, SP: Mercado de Livros. 1998<\/a><\/span><\/strong><\/p>\n<div><\/div>\n<div>Neste dia tamb\u00e9m ser\u00e1 apresentado o calend\u00e1rio de atividades deste semestre.<\/div>\n<div><\/div>\n<\/div>\n<div>Contamos com a presen\u00e7a de todos os membros, assim como dos interessados em participar \u00a0do NYEMBA.<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<hr \/>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prezados e Prezadas membros do Nyemba,\u00a0 Convidamos @ tod@s para participar da nossa primeira reuni\u00e3o do segundo semestre que acontecer\u00e1 dia\u00a010 de outubro de 2017, \u00e0s\u00a09:30 (Sala 04).\u00a0 Nesse dia iremos discutir o texto Godoi, Emilia. O sistema do lugar que faz parte das discuss\u00f5es sobre Territ\u00f3rio, Identidade e Mem\u00f3ria que ser\u00e3o levadas a cabo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[28],"class_list":["post-1097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atividades-nyemba","tag-encontro-nyemba"],"_links":{"self":[{"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/posts\/1097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/comments?post=1097"}],"version-history":[{"count":7,"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/posts\/1097\/revisions"}],"predecessor-version":[{"id":1117,"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/posts\/1097\/revisions\/1117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/media\/942"}],"wp:attachment":[{"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/media?parent=1097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/categories?post=1097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nyemba.unilab.edu.br\/index.php\/wp-json\/wp\/v2\/tags?post=1097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}